{"id":436,"date":"2017-08-07T23:14:36","date_gmt":"2017-08-07T22:14:36","guid":{"rendered":"https:\/\/www.marshals.co.uk\/midlands\/?page_id=436"},"modified":"2017-08-07T23:21:04","modified_gmt":"2017-08-07T22:21:04","slug":"bmmc-sprint-2017-curborough","status":"publish","type":"page","link":"https:\/\/www.marshals.co.uk\/midlands\/bmmc-sprint-2017-curborough\/","title":{"rendered":"BMMC Sprint 2017 &#8211; Curborough"},"content":{"rendered":"<p><a href=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/041-1-DSC_1199-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-432\" src=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/041-1-DSC_1199-3-300x155.jpg\" alt=\"\" width=\"300\" height=\"155\" srcset=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/041-1-DSC_1199-3-300x155.jpg 300w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/041-1-DSC_1199-3-768x396.jpg 768w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/041-1-DSC_1199-3-1024x528.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/043-1-DSC_1255-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-431\" src=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/043-1-DSC_1255-2-300x142.jpg\" alt=\"\" width=\"300\" height=\"142\" srcset=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/043-1-DSC_1255-2-300x142.jpg 300w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/043-1-DSC_1255-2-768x364.jpg 768w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/043-1-DSC_1255-2-1024x485.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/116-1-DSC_1349-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-429\" src=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/116-1-DSC_1349-2-300x241.jpg\" alt=\"\" width=\"300\" height=\"241\" srcset=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/116-1-DSC_1349-2-300x241.jpg 300w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/116-1-DSC_1349-2-768x616.jpg 768w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/116-1-DSC_1349-2-1024x821.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/021-1-DSC_5746-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-427\" src=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/021-1-DSC_5746-3-300x165.jpg\" alt=\"\" width=\"300\" height=\"165\" srcset=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/021-1-DSC_5746-3-300x165.jpg 300w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/021-1-DSC_5746-3-768x421.jpg 768w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/021-1-DSC_5746-3-1024x562.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/114-1-DSC_1343-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-424\" src=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/114-1-DSC_1343-1-300x230.jpg\" alt=\"\" width=\"300\" height=\"230\" srcset=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/114-1-DSC_1343-1-300x230.jpg 300w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/114-1-DSC_1343-1-768x589.jpg 768w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/114-1-DSC_1343-1-1024x786.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/085-1-DSC_1274-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-423\" src=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/085-1-DSC_1274-1-300x133.jpg\" alt=\"\" width=\"300\" height=\"133\" srcset=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/085-1-DSC_1274-1-300x133.jpg 300w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/085-1-DSC_1274-1-768x340.jpg 768w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/085-1-DSC_1274-1-1024x454.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/084-1-DSC_1271-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-422\" src=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/084-1-DSC_1271-1-300x166.jpg\" alt=\"\" width=\"300\" height=\"166\" srcset=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/084-1-DSC_1271-1-300x166.jpg 300w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/084-1-DSC_1271-1-768x425.jpg 768w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/084-1-DSC_1271-1-1024x567.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/083-1-DSC_1264-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-421\" src=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/083-1-DSC_1264-1-300x156.jpg\" alt=\"\" width=\"300\" height=\"156\" srcset=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/083-1-DSC_1264-1-300x156.jpg 300w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/083-1-DSC_1264-1-768x399.jpg 768w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/083-1-DSC_1264-1-1024x532.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/082-1-DSC_1262-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-420\" src=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/082-1-DSC_1262-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/082-1-DSC_1262-1-300x200.jpg 300w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/082-1-DSC_1262-1-768x512.jpg 768w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/082-1-DSC_1262-1-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/081-1-DSC_1260-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-419\" src=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/081-1-DSC_1260-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/081-1-DSC_1260-1-300x200.jpg 300w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/081-1-DSC_1260-1-768x512.jpg 768w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/081-1-DSC_1260-1-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/040-1-DSC_1188-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-415\" src=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/040-1-DSC_1188-1-300x158.jpg\" alt=\"\" width=\"300\" height=\"158\" srcset=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/040-1-DSC_1188-1-300x158.jpg 300w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/040-1-DSC_1188-1-768x406.jpg 768w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/040-1-DSC_1188-1-1024x541.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/069-1-DSC_6503.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-407\" src=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/069-1-DSC_6503-300x129.jpg\" alt=\"\" width=\"300\" height=\"129\" srcset=\"https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/069-1-DSC_6503-300x129.jpg 300w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/069-1-DSC_6503-768x330.jpg 768w, https:\/\/www.marshals.co.uk\/midlands\/wp-content\/uploads\/sites\/4\/2017\/08\/069-1-DSC_6503-1024x440.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":795,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-436","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.marshals.co.uk\/midlands\/wp-json\/wp\/v2\/pages\/436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marshals.co.uk\/midlands\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.marshals.co.uk\/midlands\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.marshals.co.uk\/midlands\/wp-json\/wp\/v2\/users\/795"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marshals.co.uk\/midlands\/wp-json\/wp\/v2\/comments?post=436"}],"version-history":[{"count":2,"href":"https:\/\/www.marshals.co.uk\/midlands\/wp-json\/wp\/v2\/pages\/436\/revisions"}],"predecessor-version":[{"id":441,"href":"https:\/\/www.marshals.co.uk\/midlands\/wp-json\/wp\/v2\/pages\/436\/revisions\/441"}],"wp:attachment":[{"href":"https:\/\/www.marshals.co.uk\/midlands\/wp-json\/wp\/v2\/media?parent=436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}