{"id":100,"date":"2016-02-19T02:36:51","date_gmt":"2016-02-19T02:36:51","guid":{"rendered":"https:\/\/www.marshals.co.uk\/southmidlands\/?page_id=100"},"modified":"2024-11-17T14:34:52","modified_gmt":"2024-11-17T14:34:52","slug":"marshal-of-the-year-trophy","status":"publish","type":"page","link":"https:\/\/www.marshals.co.uk\/southmidlands\/committee\/awards\/marshal-of-the-year-trophy\/","title":{"rendered":"Marshal of the Year Trophy"},"content":{"rendered":"<table width=\"60%\">\n<tbody>\n<tr>\n<th style=\"text-align: left\">Date<\/th>\n<th style=\"text-align: left\">Winner<\/th>\n<\/tr>\n<tr>\n<td>2024<\/td>\n<td>Kaz Topping<\/td>\n<\/tr>\n<tr>\n<td>2023<\/td>\n<td>Glynn Ellis<\/td>\n<\/tr>\n<tr>\n<td>2022<\/td>\n<td>Ian Greenwood<\/td>\n<\/tr>\n<tr>\n<td>2021<\/td>\n<td>Marion Quarrington<\/td>\n<\/tr>\n<tr>\n<td>2020<\/td>\n<td>Chris Whitlock<\/td>\n<\/tr>\n<tr>\n<td>2019<\/td>\n<td>\u00a0Dave Joyce<\/td>\n<\/tr>\n<tr>\n<td>2018<\/td>\n<td>\u00a0Bob Sketchley<\/td>\n<\/tr>\n<tr>\n<td>2017<\/td>\n<td>\u00a0Paul Harris<\/td>\n<\/tr>\n<tr>\n<td>2016<\/td>\n<td>\u00a0Matt Turner<\/td>\n<\/tr>\n<tr>\n<td>2015<\/td>\n<td>\u00a0Fay &amp; Alan Crook<\/td>\n<\/tr>\n<tr>\n<td>2014<\/td>\n<td>\u00a0Marion Quarringdon<\/td>\n<\/tr>\n<tr>\n<td>2013<\/td>\n<td>\u00a0Dave Reed<\/td>\n<\/tr>\n<tr>\n<td>2011<\/td>\n<td>\u00a0Malcolm Flippance<\/td>\n<\/tr>\n<tr>\n<td>2010<\/td>\n<td>\u00a0Chris Whitlock<\/td>\n<\/tr>\n<tr>\n<td>2009<\/td>\n<td>\u00a0Alan Crook<\/td>\n<\/tr>\n<tr>\n<td>2008<\/td>\n<td>\u00a0Fay Crook<\/td>\n<\/tr>\n<tr>\n<td>2007<\/td>\n<td>\u00a0Bob Sketchley<\/td>\n<\/tr>\n<tr>\n<td>2006<\/td>\n<td>\u00a0Paul Harris<\/td>\n<\/tr>\n<tr>\n<td>2005<\/td>\n<td>\u00a0Chris Whitlock<\/td>\n<\/tr>\n<tr>\n<td>2004<\/td>\n<td>\u00a0Sue Whitlock<\/td>\n<\/tr>\n<tr>\n<td>2003<\/td>\n<td>\u00a0John Newman<\/td>\n<\/tr>\n<tr>\n<td>2002<\/td>\n<td>\u00a0not awarded<\/td>\n<\/tr>\n<tr>\n<td>2001<\/td>\n<td>\u00a0Peter Cox<\/td>\n<\/tr>\n<tr>\n<td>2000<\/td>\n<td>\u00a0John Bowdler<\/td>\n<\/tr>\n<tr>\n<td>1999<\/td>\n<td>\u00a0Peter Cox<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Date Winner 2024 Kaz Topping 2023 Glynn Ellis 2022 Ian Greenwood 2021 Marion Quarrington 2020 Chris Whitlock 2019 \u00a0Dave Joyce 2018 \u00a0Bob Sketchley 2017 \u00a0Paul Harris 2016 \u00a0Matt Turner 2015 \u00a0Fay &amp; Alan Crook 2014 \u00a0Marion Quarringdon 2013 \u00a0Dave Reed 2011 \u00a0Malcolm Flippance 2010 \u00a0Chris Whitlock 2009 \u00a0Alan Crook 2008 \u00a0Fay Crook 2007 \u00a0Bob Sketchley [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":34,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-100","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.marshals.co.uk\/southmidlands\/wp-json\/wp\/v2\/pages\/100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marshals.co.uk\/southmidlands\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.marshals.co.uk\/southmidlands\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.marshals.co.uk\/southmidlands\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marshals.co.uk\/southmidlands\/wp-json\/wp\/v2\/comments?post=100"}],"version-history":[{"count":4,"href":"https:\/\/www.marshals.co.uk\/southmidlands\/wp-json\/wp\/v2\/pages\/100\/revisions"}],"predecessor-version":[{"id":1550,"href":"https:\/\/www.marshals.co.uk\/southmidlands\/wp-json\/wp\/v2\/pages\/100\/revisions\/1550"}],"up":[{"embeddable":true,"href":"https:\/\/www.marshals.co.uk\/southmidlands\/wp-json\/wp\/v2\/pages\/34"}],"wp:attachment":[{"href":"https:\/\/www.marshals.co.uk\/southmidlands\/wp-json\/wp\/v2\/media?parent=100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}